{"id":416,"date":"2023-04-16T21:10:55","date_gmt":"2023-04-17T00:10:55","guid":{"rendered":"https:\/\/lrcontabilidadegov.com.br\/?post_type=portfolio&#038;p=416"},"modified":"2023-05-05T20:13:51","modified_gmt":"2023-05-05T23:13:51","slug":"auditoria-cauc","status":"publish","type":"portfolio","link":"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/","title":{"rendered":"Auditoria CAUC"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":417,"menu_order":0,"template":"","meta":{"footnotes":""},"portfolio-cat":[13],"portfolio-tag":[4],"portfolio-filter":[5],"class_list":["post-416","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-cat-contabilidade-governamental","portfolio-tag-uncategorized","portfolio-filter-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auditoria CAUC - LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica<\/title>\n<meta name=\"description\" content=\"CAUC \u2013 Sistema Auxiliar de Informa\u00e7\u00f5es para Transfer\u00eancias Volunt\u00e1ria, entende-se por transfer\u00eancia volunt\u00e1ria a entrega de recursos correntes ou de capital a outro ente da Federa\u00e7\u00e3o, a t\u00edtulo de coopera\u00e7\u00e3o, aux\u00edlio ou assist\u00eancia financeira, que n\u00e3o decorra de determina\u00e7\u00e3o constitucional, legal ou os destinados ao Sistema \u00danico de Sa\u00fade, por meio da formaliza\u00e7\u00e3o de conv\u00eanios ou contratos de repasse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auditoria CAUC - LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica\" \/>\n<meta property=\"og:description\" content=\"CAUC \u2013 Sistema Auxiliar de Informa\u00e7\u00f5es para Transfer\u00eancias Volunt\u00e1ria, entende-se por transfer\u00eancia volunt\u00e1ria a entrega de recursos correntes ou de capital a outro ente da Federa\u00e7\u00e3o, a t\u00edtulo de coopera\u00e7\u00e3o, aux\u00edlio ou assist\u00eancia financeira, que n\u00e3o decorra de determina\u00e7\u00e3o constitucional, legal ou os destinados ao Sistema \u00danico de Sa\u00fade, por meio da formaliza\u00e7\u00e3o de conv\u00eanios ou contratos de repasse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/\" \/>\n<meta property=\"og:site_name\" content=\"LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100000390621935\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-05T23:13:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lrcontabilidadegov.com.br\/wp-content\/uploads\/2023\/04\/cauc.png\" \/>\n\t<meta property=\"og:image:width\" content=\"264\" \/>\n\t<meta property=\"og:image:height\" content=\"191\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/index.php\\\/portfolio\\\/auditoria-cauc\\\/\",\"url\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/index.php\\\/portfolio\\\/auditoria-cauc\\\/\",\"name\":\"Auditoria CAUC - LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/index.php\\\/portfolio\\\/auditoria-cauc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/index.php\\\/portfolio\\\/auditoria-cauc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/lrcontabilidadegov.com.br\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cauc.png?fit=264%2C191&ssl=1\",\"datePublished\":\"2023-04-17T00:10:55+00:00\",\"dateModified\":\"2023-05-05T23:13:51+00:00\",\"description\":\"CAUC \u2013 Sistema Auxiliar de Informa\u00e7\u00f5es para Transfer\u00eancias Volunt\u00e1ria, entende-se por transfer\u00eancia volunt\u00e1ria a entrega de recursos correntes ou de capital a outro ente da Federa\u00e7\u00e3o, a t\u00edtulo de coopera\u00e7\u00e3o, aux\u00edlio ou assist\u00eancia financeira, que n\u00e3o decorra de determina\u00e7\u00e3o constitucional, legal ou os destinados ao Sistema \u00danico de Sa\u00fade, por meio da formaliza\u00e7\u00e3o de conv\u00eanios ou contratos de repasse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/index.php\\\/portfolio\\\/auditoria-cauc\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/index.php\\\/portfolio\\\/auditoria-cauc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/index.php\\\/portfolio\\\/auditoria-cauc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/lrcontabilidadegov.com.br\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cauc.png?fit=264%2C191&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/lrcontabilidadegov.com.br\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cauc.png?fit=264%2C191&ssl=1\",\"width\":264,\"height\":191},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/index.php\\\/portfolio\\\/auditoria-cauc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolios\",\"item\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/index.php\\\/portfolio\\\/all\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Auditoria CAUC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/#website\",\"url\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/\",\"name\":\"LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica\",\"description\":\"Solu\u00e7\u00f5es para Contabilidade P\u00fablica\",\"publisher\":{\"@id\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/#organization\",\"name\":\"LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica\",\"url\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/lrcontabilidadegov.com.br\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LR-logo-1.png?fit=1216%2C150&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/lrcontabilidadegov.com.br\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LR-logo-1.png?fit=1216%2C150&ssl=1\",\"width\":1216,\"height\":150,\"caption\":\"LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica\"},\"image\":{\"@id\":\"https:\\\/\\\/lrcontabilidadegov.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100000390621935\",\"https:\\\/\\\/www.instagram.com\\\/robertovitaljunior\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auditoria CAUC - LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica","description":"CAUC \u2013 Sistema Auxiliar de Informa\u00e7\u00f5es para Transfer\u00eancias Volunt\u00e1ria, entende-se por transfer\u00eancia volunt\u00e1ria a entrega de recursos correntes ou de capital a outro ente da Federa\u00e7\u00e3o, a t\u00edtulo de coopera\u00e7\u00e3o, aux\u00edlio ou assist\u00eancia financeira, que n\u00e3o decorra de determina\u00e7\u00e3o constitucional, legal ou os destinados ao Sistema \u00danico de Sa\u00fade, por meio da formaliza\u00e7\u00e3o de conv\u00eanios ou contratos de repasse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/","og_locale":"pt_BR","og_type":"article","og_title":"Auditoria CAUC - LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica","og_description":"CAUC \u2013 Sistema Auxiliar de Informa\u00e7\u00f5es para Transfer\u00eancias Volunt\u00e1ria, entende-se por transfer\u00eancia volunt\u00e1ria a entrega de recursos correntes ou de capital a outro ente da Federa\u00e7\u00e3o, a t\u00edtulo de coopera\u00e7\u00e3o, aux\u00edlio ou assist\u00eancia financeira, que n\u00e3o decorra de determina\u00e7\u00e3o constitucional, legal ou os destinados ao Sistema \u00danico de Sa\u00fade, por meio da formaliza\u00e7\u00e3o de conv\u00eanios ou contratos de repasse.","og_url":"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/","og_site_name":"LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100000390621935","article_modified_time":"2023-05-05T23:13:51+00:00","og_image":[{"width":264,"height":191,"url":"https:\/\/lrcontabilidadegov.com.br\/wp-content\/uploads\/2023\/04\/cauc.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/","url":"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/","name":"Auditoria CAUC - LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica","isPartOf":{"@id":"https:\/\/lrcontabilidadegov.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/#primaryimage"},"image":{"@id":"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/lrcontabilidadegov.com.br\/wp-content\/uploads\/2023\/04\/cauc.png?fit=264%2C191&ssl=1","datePublished":"2023-04-17T00:10:55+00:00","dateModified":"2023-05-05T23:13:51+00:00","description":"CAUC \u2013 Sistema Auxiliar de Informa\u00e7\u00f5es para Transfer\u00eancias Volunt\u00e1ria, entende-se por transfer\u00eancia volunt\u00e1ria a entrega de recursos correntes ou de capital a outro ente da Federa\u00e7\u00e3o, a t\u00edtulo de coopera\u00e7\u00e3o, aux\u00edlio ou assist\u00eancia financeira, que n\u00e3o decorra de determina\u00e7\u00e3o constitucional, legal ou os destinados ao Sistema \u00danico de Sa\u00fade, por meio da formaliza\u00e7\u00e3o de conv\u00eanios ou contratos de repasse.","breadcrumb":{"@id":"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/#primaryimage","url":"https:\/\/i0.wp.com\/lrcontabilidadegov.com.br\/wp-content\/uploads\/2023\/04\/cauc.png?fit=264%2C191&ssl=1","contentUrl":"https:\/\/i0.wp.com\/lrcontabilidadegov.com.br\/wp-content\/uploads\/2023\/04\/cauc.png?fit=264%2C191&ssl=1","width":264,"height":191},{"@type":"BreadcrumbList","@id":"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/auditoria-cauc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lrcontabilidadegov.com.br\/"},{"@type":"ListItem","position":2,"name":"Portfolios","item":"https:\/\/lrcontabilidadegov.com.br\/index.php\/portfolio\/all\/"},{"@type":"ListItem","position":3,"name":"Auditoria CAUC"}]},{"@type":"WebSite","@id":"https:\/\/lrcontabilidadegov.com.br\/#website","url":"https:\/\/lrcontabilidadegov.com.br\/","name":"LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica","description":"Solu\u00e7\u00f5es para Contabilidade P\u00fablica","publisher":{"@id":"https:\/\/lrcontabilidadegov.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lrcontabilidadegov.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/lrcontabilidadegov.com.br\/#organization","name":"LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica","url":"https:\/\/lrcontabilidadegov.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lrcontabilidadegov.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/lrcontabilidadegov.com.br\/wp-content\/uploads\/2023\/04\/LR-logo-1.png?fit=1216%2C150&ssl=1","contentUrl":"https:\/\/i0.wp.com\/lrcontabilidadegov.com.br\/wp-content\/uploads\/2023\/04\/LR-logo-1.png?fit=1216%2C150&ssl=1","width":1216,"height":150,"caption":"LR Contabilidade e Administra\u00e7\u00e3o P\u00fablica"},"image":{"@id":"https:\/\/lrcontabilidadegov.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100000390621935","https:\/\/www.instagram.com\/robertovitaljunior\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lrcontabilidadegov.com.br\/index.php\/wp-json\/wp\/v2\/portfolio\/416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lrcontabilidadegov.com.br\/index.php\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/lrcontabilidadegov.com.br\/index.php\/wp-json\/wp\/v2\/types\/portfolio"}],"version-history":[{"count":1,"href":"https:\/\/lrcontabilidadegov.com.br\/index.php\/wp-json\/wp\/v2\/portfolio\/416\/revisions"}],"predecessor-version":[{"id":418,"href":"https:\/\/lrcontabilidadegov.com.br\/index.php\/wp-json\/wp\/v2\/portfolio\/416\/revisions\/418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lrcontabilidadegov.com.br\/index.php\/wp-json\/wp\/v2\/media\/417"}],"wp:attachment":[{"href":"https:\/\/lrcontabilidadegov.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=416"}],"wp:term":[{"taxonomy":"portfolio-cat","embeddable":true,"href":"https:\/\/lrcontabilidadegov.com.br\/index.php\/wp-json\/wp\/v2\/portfolio-cat?post=416"},{"taxonomy":"portfolio-tag","embeddable":true,"href":"https:\/\/lrcontabilidadegov.com.br\/index.php\/wp-json\/wp\/v2\/portfolio-tag?post=416"},{"taxonomy":"portfolio-filter","embeddable":true,"href":"https:\/\/lrcontabilidadegov.com.br\/index.php\/wp-json\/wp\/v2\/portfolio-filter?post=416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}